{"id":4555,"date":"2022-11-09T14:03:51","date_gmt":"2022-11-09T17:03:51","guid":{"rendered":"https:\/\/salesianossp.org.br\/osbomretiro\/?p=4555"},"modified":"2022-11-09T14:03:51","modified_gmt":"2022-11-09T17:03:51","slug":"terrario-une-jovens-e-adultos-no-idb","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/","title":{"rendered":"<strong>Terr\u00e1rio une jovens e adultos no IDB&nbsp;<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em outubro, os jovens do CCA PROVIM Bom Retiro, constru\u00edram junto com os Educadores da Pastoral, Comunica\u00e7\u00e3o e o Diretor Pe H\u00e9lio, um terr\u00e1rio. A Proposta foi uma ideia do Diretor com a Equipe do Alian\u00e7a Verde de Dom Bosco da casa. Neste dia os jovens realizaram, compreenderam e tamb\u00e9m ensinaram todo o processo e ciclo da \u00e1gua e vida nesse pequeno mundo, dentro de um aqu\u00e1rio. Foram realizados dois terr\u00e1rios, um com a turma da manh\u00e3 e outro com a galera da tarde. No dia, a turma do CEDESP tamb\u00e9m se animou e contribuiu com o plantio. O objetivo \u00e9 de que os Atendidos pudessem notar a resili\u00eancia, for\u00e7a e import\u00e2ncia da natureza, colocando a m\u00e3o na massa. Al\u00e9m da compreens\u00e3o do ciclo, a inten\u00e7\u00e3o era o contato com as plantas e que todos pudessem observar que alguns materiais que dispensamos, vidros, potes, etc, podem tornar-se um lar, como no caso do aqu\u00e1rio que estava sem uso. \u201cA plantinha carn\u00edvora certamente roubou a cena na parte da manh\u00e3. Foi muito importante realizar esse processo com a turminha, al\u00e9m de que, o terr\u00e1rio fica exposto no p\u00f3rtico, despertando ainda mais curiosos e interessados. E, \u00e9 exatamente essa sementinha que gostar\u00edamos de plantar!\u201d, concluiu Fabiana Santello da Comunica\u00e7\u00e3o.&nbsp;<br>O terr\u00e1rio foi exposto na EXPO 2022 e, em um QR-CODE mostrava como fazer o plantio e tamb\u00e9m as moradoras deste universo verde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como montar um terr\u00e1rio: <a href=\"https:\/\/bit.ly\/3fPvxWi\">https:\/\/bit.ly\/3fPvxWi<\/a><br>Quem habita os terr\u00e1rios do IDB: <a href=\"https:\/\/bit.ly\/3tgMpIE\">https:\/\/bit.ly\/3tgMpIE<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.facebook.com\/media\/set?vanity=InstitutoDomBoscoBomRetiro&amp;set=a.2228252194002448\" data-type=\"URL\" data-id=\"https:\/\/www.facebook.com\/media\/set?vanity=InstitutoDomBoscoBomRetiro&amp;set=a.2228252194002448\">Clique aqui para ver todas as fotos<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em outubro, os jovens do CCA PROVIM Bom Retiro, constru\u00edram junto com os Educadores da Pastoral, Comunica\u00e7\u00e3o e o Diretor Pe H\u00e9lio, um terr\u00e1rio. A Proposta foi uma ideia do Diretor com a Equipe do Alian\u00e7a Verde de Dom Bosco da casa. Neste dia os jovens realizaram, compreenderam e tamb\u00e9m ensinaram todo o processo e [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":4556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-4555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco\" \/>\n<meta property=\"og:description\" content=\"Em outubro, os jovens do CCA PROVIM Bom Retiro, constru\u00edram junto com os Educadores da Pastoral, Comunica\u00e7\u00e3o e o Diretor Pe H\u00e9lio, um terr\u00e1rio. A Proposta foi uma ideia do Diretor com a Equipe do Alian\u00e7a Verde de Dom Bosco da casa. Neste dia os jovens realizaram, compreenderam e tamb\u00e9m ensinaram todo o processo e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Dom Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T17:03:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/person\\\/3091f5c85d13f1f81c2eadb190445d2e\"},\"headline\":\"Terr\u00e1rio une jovens e adultos no IDB&nbsp;\",\"datePublished\":\"2022-11-09T17:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Publicacoes-IDB.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/\",\"name\":\"Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Publicacoes-IDB.jpg\",\"datePublished\":\"2022-11-09T17:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Publicacoes-IDB.jpg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Publicacoes-IDB.jpg\",\"width\":667,\"height\":668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/terrario-une-jovens-e-adultos-no-idb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terr\u00e1rio une jovens e adultos no IDB&nbsp;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\",\"name\":\"Instituto Dom Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\",\"name\":\"Instituto Dom Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-instituto-dom-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-instituto-dom-bosco-color-56.svg\",\"width\":164,\"height\":56,\"caption\":\"Instituto Dom Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InstitutoDomBoscoBomRetiro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Institutodb\",\"https:\\\/\\\/www.instagram.com\\\/institutodb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/person\\\/3091f5c85d13f1f81c2eadb190445d2e\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/","og_locale":"pt_BR","og_type":"article","og_title":"Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco","og_description":"Em outubro, os jovens do CCA PROVIM Bom Retiro, constru\u00edram junto com os Educadores da Pastoral, Comunica\u00e7\u00e3o e o Diretor Pe H\u00e9lio, um terr\u00e1rio. A Proposta foi uma ideia do Diretor com a Equipe do Alian\u00e7a Verde de Dom Bosco da casa. Neste dia os jovens realizaram, compreenderam e tamb\u00e9m ensinaram todo o processo e [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/","og_site_name":"Instituto Dom Bosco","article_publisher":"https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/","article_published_time":"2022-11-09T17:03:51+00:00","og_image":[{"width":667,"height":668,"url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg","type":"image\/jpeg"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/person\/3091f5c85d13f1f81c2eadb190445d2e"},"headline":"Terr\u00e1rio une jovens e adultos no IDB&nbsp;","datePublished":"2022-11-09T17:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/","url":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/","name":"Terr\u00e1rio une jovens e adultos no IDB&nbsp; - Instituto Dom Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg","datePublished":"2022-11-09T17:03:51+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#primaryimage","url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg","contentUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2022\/11\/Publicacoes-IDB.jpg","width":667,"height":668},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/terrario-une-jovens-e-adultos-no-idb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/osbomretiro\/"},{"@type":"ListItem","position":2,"name":"Terr\u00e1rio une jovens e adultos no IDB&nbsp;"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#website","url":"https:\/\/salesianossp.org.br\/osbomretiro\/","name":"Instituto Dom Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/osbomretiro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization","name":"Instituto Dom Bosco","url":"https:\/\/salesianossp.org.br\/osbomretiro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2025\/10\/logotipo-instituto-dom-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2025\/10\/logotipo-instituto-dom-bosco-color-56.svg","width":164,"height":56,"caption":"Instituto Dom Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/","https:\/\/www.youtube.com\/user\/Institutodb","https:\/\/www.instagram.com\/institutodb\/"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/person\/3091f5c85d13f1f81c2eadb190445d2e","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/osbomretiro\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts\/4555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/comments?post=4555"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts\/4555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/media\/4556"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/media?parent=4555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/categories?post=4555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/tags?post=4555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}