{"id":6340,"date":"2024-08-13T16:24:11","date_gmt":"2024-08-13T19:24:11","guid":{"rendered":"https:\/\/salesianossp.org.br\/osbomretiro\/?p=6340"},"modified":"2024-08-13T16:24:11","modified_gmt":"2024-08-13T19:24:11","slug":"atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/","title":{"rendered":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No dia 31 de julho, foi realizado o Torneio de Inverno e Concurso Cultural Cidade Ademar\/Pedreira \u2013 FutArte. O evento, que trouxe o lema: \u201cAmigos com respeito\u201d, foi pontualmente realizado na unidade CEU Alvarenga no Teatro Nelson Rodrigues. O evento, tem como objetivo&nbsp;envolver escolas, alunos e a comunidade na promo\u00e7\u00e3o da cultura da coopera\u00e7\u00e3o. Ele incentiva a produ\u00e7\u00e3o textual sobre temas relacionados \u00e0 realidade pr\u00f3xima, o que permite a constru\u00e7\u00e3o de conhecimentos que fomentam pr\u00e1ticas mais cooperativas durante as atividades escolares e sociais. Neste dia estiveram presentes usu\u00e1rios de todos os servi\u00e7os da Prote\u00e7\u00e3o B\u00e1sica, familiares e trabalhadores do SUAS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cForam momentos de muita de emo\u00e7\u00e3o e suspense, pois nossa Educanda Valnice Macedo Gon\u00e7alves de 75 anos, estava entre as tr\u00eas finalistas do concurso cultural na categoria 60+. Para\u00a0 nossa felicidade ela conquistou o 3\u00ba lugar em poesia com uma honrosa medalha de Bronze. Esta representatividade nos deixa orgulhosos, pois nos mostra o quanto nossos idosos s\u00e3o capazes, independentes e com autonomia. Ricos culturalmente e apesar das dificuldades com as tecnologias eles se destacam por sua resili\u00eancia di\u00e1ria.\u201d <\/em> <strong>Erica Ruiz<\/strong>, Gerente do N\u00facleo de Conviv\u00eancia do Idoso NCI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/www.facebook.com\/media\/set?vanity=InstitutoDomBoscoBomRetiro&amp;set=a.1002742088522272\" data-type=\"link\" data-id=\"https:\/\/www.facebook.com\/media\/set?vanity=InstitutoDomBoscoBomRetiro&amp;set=a.1002742088522272\">Clique aqui para ver todas as fotos<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 31 de julho, foi realizado o Torneio de Inverno e Concurso Cultural Cidade Ademar\/Pedreira \u2013 FutArte. O evento, que trouxe o lema: \u201cAmigos com respeito\u201d, foi pontualmente realizado na unidade CEU Alvarenga no Teatro Nelson Rodrigues. O evento, tem como objetivo&nbsp;envolver escolas, alunos e a comunidade na promo\u00e7\u00e3o da cultura da coopera\u00e7\u00e3o. Ele [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":6343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-6340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco\" \/>\n<meta property=\"og:description\" content=\"No dia 31 de julho, foi realizado o Torneio de Inverno e Concurso Cultural Cidade Ademar\/Pedreira \u2013 FutArte. O evento, que trouxe o lema: \u201cAmigos com respeito\u201d, foi pontualmente realizado na unidade CEU Alvarenga no Teatro Nelson Rodrigues. O evento, tem como objetivo&nbsp;envolver escolas, alunos e a comunidade na promo\u00e7\u00e3o da cultura da coopera\u00e7\u00e3o. Ele [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Dom Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T19:24:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/person\\\/3091f5c85d13f1f81c2eadb190445d2e\"},\"headline\":\"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar\",\"datePublished\":\"2024-08-13T19:24:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Post-IDB-4--scaled.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/\",\"name\":\"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Post-IDB-4--scaled.png\",\"datePublished\":\"2024-08-13T19:24:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Post-IDB-4--scaled.png\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Post-IDB-4--scaled.png\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\",\"name\":\"Instituto Dom Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#organization\",\"name\":\"Instituto Dom Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-instituto-dom-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-instituto-dom-bosco-color-56.svg\",\"width\":164,\"height\":56,\"caption\":\"Instituto Dom Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InstitutoDomBoscoBomRetiro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Institutodb\",\"https:\\\/\\\/www.instagram.com\\\/institutodb\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/#\\\/schema\\\/person\\\/3091f5c85d13f1f81c2eadb190445d2e\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/osbomretiro\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/","og_locale":"pt_BR","og_type":"article","og_title":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco","og_description":"No dia 31 de julho, foi realizado o Torneio de Inverno e Concurso Cultural Cidade Ademar\/Pedreira \u2013 FutArte. O evento, que trouxe o lema: \u201cAmigos com respeito\u201d, foi pontualmente realizado na unidade CEU Alvarenga no Teatro Nelson Rodrigues. O evento, tem como objetivo&nbsp;envolver escolas, alunos e a comunidade na promo\u00e7\u00e3o da cultura da coopera\u00e7\u00e3o. Ele [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/","og_site_name":"Instituto Dom Bosco","article_publisher":"https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/","article_published_time":"2024-08-13T19:24:11+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png","type":"image\/png"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/person\/3091f5c85d13f1f81c2eadb190445d2e"},"headline":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar","datePublished":"2024-08-13T19:24:11+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/","url":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/","name":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar - Instituto Dom Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png","datePublished":"2024-08-13T19:24:11+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#primaryimage","url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png","contentUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2024\/08\/Post-IDB-4--scaled.png","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/atendida-do-nci-conquista-medalha-de-bronze-com-sua-poesia-no-torneio-de-inverno-cidade-ademar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/osbomretiro\/"},{"@type":"ListItem","position":2,"name":"Atendida do NCI conquista medalha de Bronze com sua Poesia no Torneio de Inverno Cidade Ademar"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#website","url":"https:\/\/salesianossp.org.br\/osbomretiro\/","name":"Instituto Dom Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/osbomretiro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#organization","name":"Instituto Dom Bosco","url":"https:\/\/salesianossp.org.br\/osbomretiro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2025\/10\/logotipo-instituto-dom-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-content\/uploads\/2025\/10\/logotipo-instituto-dom-bosco-color-56.svg","width":164,"height":56,"caption":"Instituto Dom Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InstitutoDomBoscoBomRetiro\/","https:\/\/www.youtube.com\/user\/Institutodb","https:\/\/www.instagram.com\/institutodb\/"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/osbomretiro\/#\/schema\/person\/3091f5c85d13f1f81c2eadb190445d2e","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/osbomretiro\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts\/6340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/comments?post=6340"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/posts\/6340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/media\/6343"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/media?parent=6340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/categories?post=6340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/osbomretiro\/wp-json\/wp\/v2\/tags?post=6340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}