{"id":2124,"date":"2022-01-25T08:00:00","date_gmt":"2022-01-25T11:00:00","guid":{"rendered":"https:\/\/salesianossp.org.br\/ospinda\/?p=2124"},"modified":"2022-01-25T08:00:00","modified_gmt":"2022-01-25T11:00:00","slug":"programacao-do-triduo-e-festa-a-dom-bosco-2022","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/","title":{"rendered":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022"},"content":{"rendered":"\n<p>No dia 31 de janeiro celebramos a festa lit\u00fargica de S\u00e3o Jo\u00e3o Bosco, o nosso Dom Bosco, Pai e Mestre da Juventude, fundador da Fam\u00edlia Salesiana. Com seu estilo educativo e a sua pr\u00e1xis pastoral, baseados na raz\u00e3o, na religi\u00e3o e na \u201camorevolezza\u201d (Sistema Preventivo) levava os adolescentes e os jovens \u00e0 reflex\u00e3o, ao encontro com Cristo e com os irm\u00e3os, \u00e0 educa\u00e7\u00e3o da f\u00e9 e \u00e0 sua celebra\u00e7\u00e3o nos sacramentos, ao compromisso apost\u00f3lico, civil e profissional. No Centen\u00e1rio de sua morte, que aconteceu no dia 31 de janeiro de 1888, Jo\u00e3o Paulo II o declarou e proclamou Pai e Mestre da juventude.<\/p>\n\n\n\n<p>E para celebrar sua vida e miss\u00e3o, voc\u00ea \u00e9 convidado a participar do Tr\u00edduo e da Festa de 28 \u00e0 31 de janeiro. Confira a programa\u00e7\u00e3o:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022-1024x1024.png\" alt=\"\" class=\"wp-image-2125\" width=\"768\" height=\"768\" srcset=\"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022-1024x1024.png 1024w, https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022-300x300.png 300w, https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022-150x150.png 150w, https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022-768x768.png 768w, https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/Triduo-DB-2022.png 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>No dia 31, com Santa Missa presidida pelo nosso diretor, Pe. Emerson e concelebrada pela comunidade salesiana, tamb\u00e9m teremos o compromisso dos novos cooperadores salesianos e apresenta\u00e7\u00e3o dos Aspirantes 2022.<\/p>\n\n\n\n<p>Venha celebrar conosco!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 31 de janeiro celebramos a festa lit\u00fargica de S\u00e3o Jo\u00e3o Bosco, o nosso Dom Bosco, Pai e Mestre da Juventude, fundador da Fam\u00edlia Salesiana. Com seu estilo educativo e a sua pr\u00e1xis pastoral, baseados na raz\u00e3o, na religi\u00e3o e na \u201camorevolezza\u201d (Sistema Preventivo) levava os adolescentes e os jovens \u00e0 reflex\u00e3o, ao encontro [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":2128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[396,277,395,415],"class_list":["post-2124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-dombosco","tag-festa","tag-salesianospinda","tag-triduo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano\" \/>\n<meta property=\"og:description\" content=\"No dia 31 de janeiro celebramos a festa lit\u00fargica de S\u00e3o Jo\u00e3o Bosco, o nosso Dom Bosco, Pai e Mestre da Juventude, fundador da Fam\u00edlia Salesiana. Com seu estilo educativo e a sua pr\u00e1xis pastoral, baseados na raz\u00e3o, na religi\u00e3o e na \u201camorevolezza\u201d (Sistema Preventivo) levava os adolescentes e os jovens \u00e0 reflex\u00e3o, ao encontro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Social Salesiano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalesianosPindamonhangaba\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/person\\\/b86a68b474cba608510836b3edec8fb7\"},\"headline\":\"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022\",\"datePublished\":\"2022-01-25T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/\"},\"wordCount\":179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/triduomat22.png\",\"keywords\":[\"dombosco\",\"festa\",\"SalesianosPinda\",\"triduo\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/\",\"name\":\"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/triduomat22.png\",\"datePublished\":\"2022-01-25T11:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/triduomat22.png\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/triduomat22.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/2022\\\/01\\\/25\\\/programacao-do-triduo-e-festa-a-dom-bosco-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\",\"name\":\"Centro Social Salesiano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#organization\",\"name\":\"Centro Social Salesiano\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-centro-social-salesiano-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-centro-social-salesiano-color-56.svg\",\"width\":232,\"height\":56,\"caption\":\"Centro Social Salesiano\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalesianosPindamonhangaba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC3MLkAU0c9laaRk8ygugbrA\",\"https:\\\/\\\/www.instagram.com\\\/salesianos.pindaoficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/person\\\/b86a68b474cba608510836b3edec8fb7\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano","og_description":"No dia 31 de janeiro celebramos a festa lit\u00fargica de S\u00e3o Jo\u00e3o Bosco, o nosso Dom Bosco, Pai e Mestre da Juventude, fundador da Fam\u00edlia Salesiana. Com seu estilo educativo e a sua pr\u00e1xis pastoral, baseados na raz\u00e3o, na religi\u00e3o e na \u201camorevolezza\u201d (Sistema Preventivo) levava os adolescentes e os jovens \u00e0 reflex\u00e3o, ao encontro [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/","og_site_name":"Centro Social Salesiano","article_publisher":"https:\/\/www.facebook.com\/SalesianosPindamonhangaba\/","article_published_time":"2022-01-25T11:00:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png","type":"image\/png"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/person\/b86a68b474cba608510836b3edec8fb7"},"headline":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022","datePublished":"2022-01-25T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/"},"wordCount":179,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png","keywords":["dombosco","festa","SalesianosPinda","triduo"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/","url":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/","name":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022 - Centro Social Salesiano","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png","datePublished":"2022-01-25T11:00:00+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#primaryimage","url":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png","contentUrl":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2022\/01\/triduomat22.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ospinda\/2022\/01\/25\/programacao-do-triduo-e-festa-a-dom-bosco-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ospinda\/"},{"@type":"ListItem","position":2,"name":"Programa\u00e7\u00e3o do Tr\u00edduo e festa a Dom Bosco 2022"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ospinda\/#website","url":"https:\/\/salesianossp.org.br\/ospinda\/","name":"Centro Social Salesiano","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ospinda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ospinda\/#organization","name":"Centro Social Salesiano","url":"https:\/\/salesianossp.org.br\/ospinda\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2025\/10\/logotipo-centro-social-salesiano-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2025\/10\/logotipo-centro-social-salesiano-color-56.svg","width":232,"height":56,"caption":"Centro Social Salesiano"},"image":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalesianosPindamonhangaba\/","https:\/\/www.youtube.com\/channel\/UC3MLkAU0c9laaRk8ygugbrA","https:\/\/www.instagram.com\/salesianos.pindaoficial\/"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/person\/b86a68b474cba608510836b3edec8fb7","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/ospinda\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/posts\/2124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/comments?post=2124"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/posts\/2124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/media\/2128"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/media?parent=2124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/categories?post=2124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/tags?post=2124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}