{"id":413,"count":1,"description":"","link":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/","name":"assistenciasocial","slug":"assistenciasocial","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de assistenciasocial - Centro Social Salesiano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de assistenciasocial - Centro Social Salesiano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Social Salesiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/tag\\\/assistenciasocial\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/tag\\\/assistenciasocial\\\/\",\"name\":\"Arquivo de assistenciasocial - Centro Social Salesiano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/tag\\\/assistenciasocial\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/tag\\\/assistenciasocial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"assistenciasocial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\",\"name\":\"Centro Social Salesiano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#organization\",\"name\":\"Centro Social Salesiano\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-centro-social-salesiano-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-centro-social-salesiano-color-56.svg\",\"width\":232,\"height\":56,\"caption\":\"Centro Social Salesiano\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ospinda\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalesianosPindamonhangaba\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC3MLkAU0c9laaRk8ygugbrA\",\"https:\\\/\\\/www.instagram.com\\\/salesianos.pindaoficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de assistenciasocial - Centro Social Salesiano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de assistenciasocial - Centro Social Salesiano","og_url":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/","og_site_name":"Centro Social Salesiano","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/","url":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/","name":"Arquivo de assistenciasocial - Centro Social Salesiano","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#website"},"breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ospinda\/tag\/assistenciasocial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ospinda\/"},{"@type":"ListItem","position":2,"name":"assistenciasocial"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ospinda\/#website","url":"https:\/\/salesianossp.org.br\/ospinda\/","name":"Centro Social Salesiano","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ospinda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ospinda\/#organization","name":"Centro Social Salesiano","url":"https:\/\/salesianossp.org.br\/ospinda\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2025\/10\/logotipo-centro-social-salesiano-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ospinda\/wp-content\/uploads\/2025\/10\/logotipo-centro-social-salesiano-color-56.svg","width":232,"height":56,"caption":"Centro Social Salesiano"},"image":{"@id":"https:\/\/salesianossp.org.br\/ospinda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalesianosPindamonhangaba\/","https:\/\/www.youtube.com\/channel\/UC3MLkAU0c9laaRk8ygugbrA","https:\/\/www.instagram.com\/salesianos.pindaoficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/tags\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/salesianossp.org.br\/ospinda\/wp-json\/wp\/v2\/posts?tags=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}