{"id":117455,"date":"2025-11-06T19:56:34","date_gmt":"2025-11-06T19:56:34","guid":{"rendered":"https:\/\/salesianossp.org.br\/ossjb\/?p=117455"},"modified":"2025-11-06T19:56:36","modified_gmt":"2025-11-06T19:56:36","slug":"oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/","title":{"rendered":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\"><em>Educadores apresentam a\u00e7\u00f5es educativas que transformam as atividades di\u00e1rias a outros colaboradores<\/em><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Na sexta-feira, 31 de outubro, os colaboradores da Obra Social S\u00e3o Jo\u00e3o Bosco se reuniram para sua forma\u00e7\u00e3o mensal e puderam compreender algumas das boas pr\u00e1ticas executadas em nossas unidades de atendimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seis educadores, um de cada unidade da Obra, apresentaram aos outros colaboradores algumas de suas pr\u00e1ticas educativas. Os presentes puderam escolher as oficinas que iriam participar e aprenderam mais sobre como agir no dia a dia da organiza\u00e7\u00e3o, al\u00e9m de serem inspirados por ideias vindas de seus colegas de outras localidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja abaixo as boas pr\u00e1ticas que foram apresentadas nesta forma\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1024x768.jpeg\" alt=\"\" class=\"wp-image-117456\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Pilates \u2013 Ivan (educador na unidade Dom Bosco)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Ivan teve a miss\u00e3o de apresentar uma das atividades que desenvolve enquanto educador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Pilates \u00e9 a pr\u00e1tica do exerc\u00edcio f\u00edsico para condicionamento, com movimentos controlados de baixo impacto e utilizando o solo e alguns equipamentos. A pr\u00e1tica do Pilates melhora a for\u00e7a, a resist\u00eancia, a flexibilidade e a consci\u00eancia corporal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1024x768.jpeg\" alt=\"\" class=\"wp-image-117457\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Psicomotricidade &#8211; D\u00e9bora (educadora no CEI Darcy Ribeiro)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9bora mostrou, na pr\u00e1tica, alguns exerc\u00edcios f\u00edsicos, brincadeiras, atividades e circuitos que estimulam a coordena\u00e7\u00e3o motora, a mem\u00f3ria, a aten\u00e7\u00e3o e o agir de nossos atendidos, habilidades que devem ser treinadas em todas as idades.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1024x768.jpeg\" alt=\"\" class=\"wp-image-117458\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Emocion\u00e1rio \u2013 Beatriz (educadora na unidade S\u00e3o Jo\u00e3o Batista)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Beatriz desenvolveu duas atividades em sua oficina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira foi o Emocion\u00f4metro, um quadro com algumas emo\u00e7\u00f5es que os presentes preencheram. Essa atividade estimula o educando a pensar sobre o que est\u00e1 sentindo naquele momento e entender como vai agir em rela\u00e7\u00e3o a este sentimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A atividade seguinte foi a produ\u00e7\u00e3o da \u201cGarrafinha da Calma\u201d, uma forma artesanal de fabricar um elemento com cores, texturas e materiais que ajudam na autorregula\u00e7\u00e3o do educando.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117459\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Jogos teatrais &#8211; Luis (educador na unidade Nossa Senhora Auxiliadora)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Luis acolheu os presentes e prop\u00f4s a execu\u00e7\u00e3o de algumas brincadeiras e jogos de express\u00e3o e atua\u00e7\u00e3o para fazer com os educandos em diferentes momentos. A ideia \u00e9 desenvolver habilidades como criatividade, imagina\u00e7\u00e3o, express\u00e3o corporal, resposta r\u00e1pida, improvisa\u00e7\u00e3o e questionamentos, a fim de que eles possam se comunicar melhor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117460\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>O brincar\/ fantoches \u2013 Fernanda e Camila (educadores no CEI Francisco Amaral)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">As educadoras trouxeram ideias e exemplos que trabalham a coordena\u00e7\u00e3o motora com brincadeiras, jogos e objetos feitos com materiais recicl\u00e1veis. Al\u00e9m da produ\u00e7\u00e3o desses materiais junto com os presentes, Camila e Fernanda trouxeram exemplos para serem aplicados a diferentes idades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os fantoches, tamb\u00e9m produzidos com materiais recicl\u00e1veis, foram feitos em diferentes tamanhos para que os pequenos possam explorar e aprender a manusear.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1024x768.jpeg\" alt=\"\" class=\"wp-image-117461\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Vivenciando a inclus\u00e3o na pr\u00e1tica di\u00e1ria \u2013 Samara (educadora no CEI Dom Bosquinho)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Samara \u00e9 professora da Educa\u00e7\u00e3o Especial e promove atividades diferenciadas a seus educandos com algum tipo de defici\u00eancia. Assim, ela trouxe a pr\u00e1tica di\u00e1ria para esta oficina, com ideias e exemplos do que \u00e9 executado e o porqu\u00ea dessa a\u00e7\u00e3o a depender do educando. Al\u00e9m disso, a educadora sugeriu o uso de alguns livros e de diversas atividades que podem ser desenvolvidas com os atendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que alegria podermos compartilhar nossas boas pr\u00e1ticas e auxiliar a equipe na promo\u00e7\u00e3o de uma educa\u00e7\u00e3o que acolhe. Aos educadores respons\u00e1veis pelas oficinas, nossa gratid\u00e3o por este momento de partilha e por tudo o que fazem acontecer dentro de nossas unidades e diretamente com nossos atendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que possamos ter mais momentos para expressar o bem que fazemos!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117464\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4-1024x768.jpeg\" alt=\"\" class=\"wp-image-117464\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-4.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117462\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5-1024x768.jpeg\" alt=\"\" class=\"wp-image-117462\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-5.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117463\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117463\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-6-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117465\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7-1024x768.jpeg\" alt=\"\" class=\"wp-image-117465\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-7.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117466\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8-1024x768.jpeg\" alt=\"\" class=\"wp-image-117466\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-8.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117467\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12-1024x768.jpeg\" alt=\"\" class=\"wp-image-117467\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-12.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117468\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13-1024x768.jpeg\" alt=\"\" class=\"wp-image-117468\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-13.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117469\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14-1024x768.jpeg\" alt=\"\" class=\"wp-image-117469\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-de-Outubro-Oficina-Vivenciando-a-Inclusao-14.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117470\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117470\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-1-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117471\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-117471\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117472\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5-1024x768.jpeg\" alt=\"\" class=\"wp-image-117472\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-5.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117473\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7-1024x768.jpeg\" alt=\"\" class=\"wp-image-117473\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-7.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117474\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8-1024x768.jpeg\" alt=\"\" class=\"wp-image-117474\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-8.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117475\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10-1024x768.jpeg\" alt=\"\" class=\"wp-image-117475\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-10.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117477\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13-1024x768.jpeg\" alt=\"\" class=\"wp-image-117477\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117476\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16-1024x768.jpeg\" alt=\"\" class=\"wp-image-117476\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-16.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117478\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-117478\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-2.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117483\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-117483\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117479\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117479\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-4-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117481\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7-1024x768.jpeg\" alt=\"\" class=\"wp-image-117481\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-7.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117482\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9-1024x768.jpeg\" alt=\"\" class=\"wp-image-117482\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-9.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117480\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10-1024x768.jpeg\" alt=\"\" class=\"wp-image-117480\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Emocionario-10.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117484\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117484\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-1-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117485\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-117485\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Jogos-Teatrais-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117486\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117486\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117487\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-117487\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117488\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117488\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-4-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117489\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5-1024x768.jpeg\" alt=\"\" class=\"wp-image-117489\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Pilates-5.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117491\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117491\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117492\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3-1024x768.jpeg\" alt=\"\" class=\"wp-image-117492\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-3.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117490\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-117490\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-4-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117493\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7-1024x768.jpeg\" alt=\"\" class=\"wp-image-117493\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-7.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117495\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9-1024x768.jpeg\" alt=\"\" class=\"wp-image-117495\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-9.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117494\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11-1024x768.jpeg\" alt=\"\" class=\"wp-image-117494\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-11.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"117496\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13-1024x768.jpeg\" alt=\"\" class=\"wp-image-117496\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13-1024x768.jpeg 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13-300x225.jpeg 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13-768x576.jpeg 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13-1536x1152.jpeg 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Psicomotricidade-13.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Texto e fotos: <\/strong>Mariana Ign\u00e1cio<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Educadores apresentam a\u00e7\u00f5es educativas que transformam as atividades di\u00e1rias a outros colaboradores Na sexta-feira, 31 de outubro, os colaboradores da Obra Social S\u00e3o Jo\u00e3o Bosco se reuniram para sua forma\u00e7\u00e3o mensal e puderam compreender algumas das boas pr\u00e1ticas executadas em nossas unidades de atendimento. Seis educadores, um de cada unidade da Obra, apresentaram aos outros [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":117477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,64],"tags":[530,253,531,252,394],"class_list":["post-117455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-acao-social","tag-boas-praticas","tag-campinas","tag-colaboradores","tag-formacao","tag-salesianos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"og:description\" content=\"Educadores apresentam a\u00e7\u00f5es educativas que transformam as atividades di\u00e1rias a outros colaboradores Na sexta-feira, 31 de outubro, os colaboradores da Obra Social S\u00e3o Jo\u00e3o Bosco se reuniram para sua forma\u00e7\u00e3o mensal e puderam compreender algumas das boas pr\u00e1ticas executadas em nossas unidades de atendimento. Seis educadores, um de cada unidade da Obra, apresentaram aos outros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/\" \/>\n<meta property=\"og:site_name\" content=\"Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSSJBCampinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T19:56:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Ignacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Ignacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/\"},\"author\":{\"name\":\"Mariana Ignacio\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/95c8857357b03b5655c71b112504ee4e\"},\"headline\":\"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados\",\"datePublished\":\"2025-11-06T19:56:34+00:00\",\"dateModified\":\"2025-11-06T19:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg\",\"keywords\":[\"boas pr\u00e1ticas\",\"Campinas\",\"colaboradores\",\"forma\u00e7\u00e3o\",\"salesianos\"],\"articleSection\":[\"Not\u00edcias\",\"Not\u00edcias - A\u00e7\u00e3o Social\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/\",\"name\":\"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg\",\"datePublished\":\"2025-11-06T19:56:34+00:00\",\"dateModified\":\"2025-11-06T19:56:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"width\":185,\"height\":56,\"caption\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSJBCampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ossjbcampinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClNa7qdZCtP9uzs5b0nG2LQ\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/95c8857357b03b5655c71b112504ee4e\",\"name\":\"Mariana Ignacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g\",\"caption\":\"Mariana Ignacio\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/author\\\/mariana-ignacio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/","og_locale":"pt_BR","og_type":"article","og_title":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco","og_description":"Educadores apresentam a\u00e7\u00f5es educativas que transformam as atividades di\u00e1rias a outros colaboradores Na sexta-feira, 31 de outubro, os colaboradores da Obra Social S\u00e3o Jo\u00e3o Bosco se reuniram para sua forma\u00e7\u00e3o mensal e puderam compreender algumas das boas pr\u00e1ticas executadas em nossas unidades de atendimento. Seis educadores, um de cada unidade da Obra, apresentaram aos outros [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/","og_site_name":"Obra Social S\u00e3o Jo\u00e3o Bosco","article_publisher":"https:\/\/www.facebook.com\/OSSJBCampinas\/","article_published_time":"2025-11-06T19:56:34+00:00","article_modified_time":"2025-11-06T19:56:36+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg","type":"image\/jpeg"}],"author":"Mariana Ignacio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mariana Ignacio","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/"},"author":{"name":"Mariana Ignacio","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/95c8857357b03b5655c71b112504ee4e"},"headline":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados","datePublished":"2025-11-06T19:56:34+00:00","dateModified":"2025-11-06T19:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg","keywords":["boas pr\u00e1ticas","Campinas","colaboradores","forma\u00e7\u00e3o","salesianos"],"articleSection":["Not\u00edcias","Not\u00edcias - A\u00e7\u00e3o Social"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/","url":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/","name":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados - Obra Social S\u00e3o Jo\u00e3o Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg","datePublished":"2025-11-06T19:56:34+00:00","dateModified":"2025-11-06T19:56:36+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#primaryimage","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/11\/Formacao-Outubro-Oficina-Brincar-e-Fantoches-13.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ossjb\/oficinas-de-boas-praticas-colaboradores-da-obra-participam-de-momento-de-partilha-e-aprendizados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ossjb\/"},{"@type":"ListItem","position":2,"name":"Oficinas de Boas Pr\u00e1ticas: colaboradores da Obra participam de momento de partilha e aprendizados"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ossjb\/#website","url":"https:\/\/salesianossp.org.br\/ossjb\/","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ossjb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","url":"https:\/\/salesianossp.org.br\/ossjb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","width":185,"height":56,"caption":"Obra Social S\u00e3o Jo\u00e3o Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSJBCampinas\/","https:\/\/www.instagram.com\/ossjbcampinas\/","https:\/\/www.youtube.com\/channel\/UClNa7qdZCtP9uzs5b0nG2LQ\/featured"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/95c8857357b03b5655c71b112504ee4e","name":"Mariana Ignacio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/813c248604f132855ac2ca8af114f1c0ee8d102370e673382cfa71fb85e18b5f?s=96&d=mm&r=g","caption":"Mariana Ignacio"},"url":"https:\/\/salesianossp.org.br\/ossjb\/author\/mariana-ignacio\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/117455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/comments?post=117455"}],"version-history":[{"count":1,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/117455\/revisions"}],"predecessor-version":[{"id":117497,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/117455\/revisions\/117497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media\/117477"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media?parent=117455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/categories?post=117455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags?post=117455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}