{"id":1813,"date":"2021-03-28T07:00:00","date_gmt":"2021-03-28T10:00:00","guid":{"rendered":"https:\/\/salesianossp.org.br\/ossjb\/?p=1813"},"modified":"2021-03-28T07:00:00","modified_gmt":"2021-03-28T10:00:00","slug":"como-celebrar-o-domingo-de-ramos","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/","title":{"rendered":"Como celebrar o Domingo de Ramos"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\"><strong><em>Por Pastoral Juvenil Salesiana<\/em><\/strong><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">A celebra\u00e7\u00e3o de hoje d\u00e1 inicio a Semana Santa. Ela \u00e9 dividida em duas partes: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1) Comemora\u00e7\u00e3o da entrada de Jesus em Jerusal\u00e9m, com ben\u00e7\u00e3o dos ramos em prociss\u00e3o; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2) Celebra\u00e7\u00e3o da Eucaristia, com a narra\u00e7\u00e3o da Paix\u00e3o. Estes dois aspectos da celebra\u00e7\u00e3o de hoje d\u00e3o um car\u00e1ter de antecipa\u00e7\u00e3o figurada da Pascoa: as multid\u00f5es aclamam o Cristo vencedor em sua Paix\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste dia celebramos as duas tradi\u00e7\u00f5es lit\u00fargicas que deram origem a esta ce\u00adlebra\u00e7\u00e3o: A alegre, grandiosa e festiva liturgia da entrada de Jesus em Jerusal\u00e9m, e a austera mem\u00f3ria da Paix\u00e3o de Jesus. S\u00e3o duas tradi\u00e7\u00f5es (de Jerusal\u00e9m e de Roma) que atualmente s\u00e3o celebradas juntas. S\u00e3o dois os Evangelhos desta celebra\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira tradi\u00e7\u00e3o, de Jerusal\u00e9m, (que celebramos com o primeiro evangelho) relembra o gesto prof\u00e9tico de Jesus que entra como Rei pac\u00edfico, aclamado como Messias, aquele que vem em nome do Senhor para depois ser condenado e cum\u00adprir em tudo as profecias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na segunda tradi\u00e7\u00e3o, de Roma, (que celebramos com o segundo Evangelho) encontramos a Paix\u00e3o e antecipamos a pro\u00adclama\u00e7\u00e3o do Mist\u00e9rio, com um grande contraste entre o caminho triunfante do Cristo do Domingo de Ramos e a \u201cvia crucis\u201d dos dias santos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os ramos verdes utilizados s\u00e3o o sinal da alegria pela vit\u00f3ria de Cristo. Jesus entra na cidade e \u00e9 aclamado como Rei. Ele salvar\u00e1 o povo n\u00e3o por meio da viol\u00eancia e do sacrif\u00edcio, mas com a doa\u00e7\u00e3o da pr\u00f3pria vida. Por isso cantamos forte: Hosana ao Filho de Davi. Hosana nas alturas! Bendito o que vem em nome do Senhor! Jesus \u00e9 nosso rei. Geralmente s\u00e3o utilizados galhos de palmeiras e oliveiras, mas nada impede que utilizemos ramos de outras plantas. A prociss\u00e3o simboliza o ato de avan\u00e7ar, ou seja, de caminhar rumo a Deus. A cor lit\u00fargica do dia \u00e9 vermelha, que indica a Paix\u00e3o de Cristo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste contexto de pandemia tamb\u00e9m sugerimos um esquema de celebra\u00e7\u00e3o que est\u00e1 anexo. Que voc\u00ea possa celebrar em fam\u00edlia este dia t\u00e3o importante para n\u00f3s crist\u00e3os.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/1-DOMINGO-DE-RAMOS.pdf\">1-DOMINGO-DE-RAMOS<\/a><a href=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/1-DOMINGO-DE-RAMOS.pdf\" class=\"wp-block-file__button\">Baixar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Pastoral Juvenil Salesiana A celebra\u00e7\u00e3o de hoje d\u00e1 inicio a Semana Santa. Ela \u00e9 dividida em duas partes: 1) Comemora\u00e7\u00e3o da entrada de Jesus em Jerusal\u00e9m, com ben\u00e7\u00e3o dos ramos em prociss\u00e3o; 2) Celebra\u00e7\u00e3o da Eucaristia, com a narra\u00e7\u00e3o da Paix\u00e3o. Estes dois aspectos da celebra\u00e7\u00e3o de hoje d\u00e3o um car\u00e1ter de antecipa\u00e7\u00e3o figurada [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":1815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423,422,393],"tags":[44,447,189,192,448,165,394],"class_list":["post-1813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-espiritualidade-salesiana","category-eventos","tag-dom-bosco","tag-domingo","tag-pascoa","tag-pastoral","tag-ramos","tag-salesianidade-2","tag-salesianos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"og:description\" content=\"Por Pastoral Juvenil Salesiana A celebra\u00e7\u00e3o de hoje d\u00e1 inicio a Semana Santa. Ela \u00e9 dividida em duas partes: 1) Comemora\u00e7\u00e3o da entrada de Jesus em Jerusal\u00e9m, com ben\u00e7\u00e3o dos ramos em prociss\u00e3o; 2) Celebra\u00e7\u00e3o da Eucaristia, com a narra\u00e7\u00e3o da Paix\u00e3o. Estes dois aspectos da celebra\u00e7\u00e3o de hoje d\u00e3o um car\u00e1ter de antecipa\u00e7\u00e3o figurada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/\" \/>\n<meta property=\"og:site_name\" content=\"Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSSJBCampinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-28T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\"},\"headline\":\"Como celebrar o Domingo de Ramos\",\"datePublished\":\"2021-03-28T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Hosana-ao-Filho-de-Davi.png\",\"keywords\":[\"Dom Bosco\",\"domingo\",\"P\u00e1scoa\",\"Pastoral\",\"ramos\",\"salesianidade\",\"salesianos\"],\"articleSection\":[\"Artigos\",\"Espiritualidade Salesiana\",\"Eventos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/\",\"name\":\"Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Hosana-ao-Filho-de-Davi.png\",\"datePublished\":\"2021-03-28T10:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Hosana-ao-Filho-de-Davi.png\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Hosana-ao-Filho-de-Davi.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/como-celebrar-o-domingo-de-ramos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como celebrar o Domingo de Ramos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"width\":185,\"height\":56,\"caption\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSJBCampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ossjbcampinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClNa7qdZCtP9uzs5b0nG2LQ\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/","og_locale":"pt_BR","og_type":"article","og_title":"Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco","og_description":"Por Pastoral Juvenil Salesiana A celebra\u00e7\u00e3o de hoje d\u00e1 inicio a Semana Santa. Ela \u00e9 dividida em duas partes: 1) Comemora\u00e7\u00e3o da entrada de Jesus em Jerusal\u00e9m, com ben\u00e7\u00e3o dos ramos em prociss\u00e3o; 2) Celebra\u00e7\u00e3o da Eucaristia, com a narra\u00e7\u00e3o da Paix\u00e3o. Estes dois aspectos da celebra\u00e7\u00e3o de hoje d\u00e3o um car\u00e1ter de antecipa\u00e7\u00e3o figurada [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/","og_site_name":"Obra Social S\u00e3o Jo\u00e3o Bosco","article_publisher":"https:\/\/www.facebook.com\/OSSJBCampinas\/","article_published_time":"2021-03-28T10:00:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi-1024x576.png","type":"image\/png"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93"},"headline":"Como celebrar o Domingo de Ramos","datePublished":"2021-03-28T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi.png","keywords":["Dom Bosco","domingo","P\u00e1scoa","Pastoral","ramos","salesianidade","salesianos"],"articleSection":["Artigos","Espiritualidade Salesiana","Eventos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/","url":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/","name":"Como celebrar o Domingo de Ramos - Obra Social S\u00e3o Jo\u00e3o Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi.png","datePublished":"2021-03-28T10:00:00+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#primaryimage","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi.png","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2021\/03\/Hosana-ao-Filho-de-Davi.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ossjb\/como-celebrar-o-domingo-de-ramos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ossjb\/"},{"@type":"ListItem","position":2,"name":"Como celebrar o Domingo de Ramos"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ossjb\/#website","url":"https:\/\/salesianossp.org.br\/ossjb\/","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ossjb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","url":"https:\/\/salesianossp.org.br\/ossjb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","width":185,"height":56,"caption":"Obra Social S\u00e3o Jo\u00e3o Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSJBCampinas\/","https:\/\/www.instagram.com\/ossjbcampinas\/","https:\/\/www.youtube.com\/channel\/UClNa7qdZCtP9uzs5b0nG2LQ\/featured"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/ossjb\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/1813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/1813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media\/1815"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media?parent=1813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/categories?post=1813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags?post=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}