{"id":5806,"date":"2024-01-26T19:30:39","date_gmt":"2024-01-26T22:30:39","guid":{"rendered":"https:\/\/salesianossp.org.br\/ossjb\/?p=5806"},"modified":"2024-01-26T19:30:39","modified_gmt":"2024-01-26T22:30:39","slug":"acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/","title":{"rendered":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\"><em>Educadoras da entidade refletiram o tema com os demais colaboradores na primeira forma\u00e7\u00e3o do ano<\/em><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O primeiro momento formativo da Obra Social S\u00e3o Jo\u00e3o Bosco come\u00e7ou pretendendo ajudar no planejamento das a\u00e7\u00f5es do ano, o que passa pelos relacionamentos com os educandos e com os colegas de trabalho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As educadoras Jacqueline Vieira Mattos e Patr\u00edcia de Oliveira Duarte abordaram a tem\u00e1tica do acolhimento emocional, algo que deve fazer parte da rotina dos educadores. Essa quest\u00e3o \u00e9 muito importante e, inclusive, parte importante das atitudes pedag\u00f3gicas que todo educador salesiano deve ter com seus educandos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Colocando situa\u00e7\u00f5es di\u00e1rias em reflex\u00e3o, as educadoras orientaram os mais de 200 colaboradores presentes com alguns passos que podem ser seguidos para que o acolhimento seja realizado de maneira integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, as palestrantes colocarem quest\u00f5es importantes como o fato de que acolher \u00e9 escutar, observar e respeitar, sem tentar dar uma solu\u00e7\u00e3o imediata ao problema que est\u00e3o ouvindo. Tamb\u00e9m colocaram a import\u00e2ncia de ter empatia, desarmar-se de preconceitos e respeitar o sil\u00eancio daquele que precisa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional-1024x576.png\" alt=\"\" class=\"wp-image-5808\" style=\"aspect-ratio:1.7777777777777777;width:840px;height:auto\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional-1024x576.png 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional-300x169.png 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional-768x432.png 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional-1536x864.png 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Colaboradores-discutem-acolhimento-emocional.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Durante o momento formativo, mais de 200 educadores puderam refletir sobre situa\u00e7\u00f5es di\u00e1rias que vivenciam<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cada educando tem um jeito de ser e isso tamb\u00e9m precisa ser considerado na hora do acolhimento. Ouvir \u00e9 importante, mas o acolhimento pode ser feito de outras maneiras, sobretudo quando a crian\u00e7a ou adolescente \u00e9 mais retra\u00eddo ou tem outras formas de expressar seus sentimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As palavras utilizadas pelo educador para lidar com as situa\u00e7\u00f5es que precisam de um acolhimento tamb\u00e9m s\u00e3o muito importantes. Mostrar que se importa com o sofrimento do educando, n\u00e3o desdenhar do sentimento e buscar utilizar palavras que permitam que a crian\u00e7a ou o adolescente se expresse, s\u00e3o pontos importantes para que o educando se sinta acolhido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da maneira que for, acolher \u00e9 miss\u00e3o de cada educador salesiano e saber como fazer isso \u00e9 importante para que nossos educandos se sintam bem em nossa casa.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Por Mariana Ignacio &#8211; Jornalista e Comunicadora <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Educadoras da entidade refletiram o tema com os demais colaboradores na primeira forma\u00e7\u00e3o do ano O primeiro momento formativo da Obra Social S\u00e3o Jo\u00e3o Bosco come\u00e7ou pretendendo ajudar no planejamento das a\u00e7\u00f5es do ano, o que passa pelos relacionamentos com os educandos e com os colegas de trabalho. As educadoras Jacqueline Vieira Mattos e Patr\u00edcia [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":5807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[391],"tags":[513,253,88,252,407,394],"class_list":["post-5806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informativos-ossjb","tag-acolhimento-emocional","tag-campinas","tag-educacao","tag-formacao","tag-ossjb","tag-salesianos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"og:description\" content=\"Educadoras da entidade refletiram o tema com os demais colaboradores na primeira forma\u00e7\u00e3o do ano O primeiro momento formativo da Obra Social S\u00e3o Jo\u00e3o Bosco come\u00e7ou pretendendo ajudar no planejamento das a\u00e7\u00f5es do ano, o que passa pelos relacionamentos com os educandos e com os colegas de trabalho. As educadoras Jacqueline Vieira Mattos e Patr\u00edcia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/\" \/>\n<meta property=\"og:site_name\" content=\"Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSSJBCampinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T22:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\"},\"headline\":\"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco\",\"datePublished\":\"2024-01-26T22:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png\",\"keywords\":[\"acolhimento emocional\",\"Campinas\",\"Educa\u00e7\u00e3o\",\"forma\u00e7\u00e3o\",\"OSSJB\",\"salesianos\"],\"articleSection\":[\"Informativos OSSJB\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/\",\"name\":\"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png\",\"datePublished\":\"2024-01-26T22:30:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"width\":185,\"height\":56,\"caption\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSJBCampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ossjbcampinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClNa7qdZCtP9uzs5b0nG2LQ\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/","og_locale":"pt_BR","og_type":"article","og_title":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco","og_description":"Educadoras da entidade refletiram o tema com os demais colaboradores na primeira forma\u00e7\u00e3o do ano O primeiro momento formativo da Obra Social S\u00e3o Jo\u00e3o Bosco come\u00e7ou pretendendo ajudar no planejamento das a\u00e7\u00f5es do ano, o que passa pelos relacionamentos com os educandos e com os colegas de trabalho. As educadoras Jacqueline Vieira Mattos e Patr\u00edcia [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/","og_site_name":"Obra Social S\u00e3o Jo\u00e3o Bosco","article_publisher":"https:\/\/www.facebook.com\/OSSJBCampinas\/","article_published_time":"2024-01-26T22:30:39+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional-1024x576.png","type":"image\/png"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93"},"headline":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco","datePublished":"2024-01-26T22:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png","keywords":["acolhimento emocional","Campinas","Educa\u00e7\u00e3o","forma\u00e7\u00e3o","OSSJB","salesianos"],"articleSection":["Informativos OSSJB"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/","url":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/","name":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco - Obra Social S\u00e3o Jo\u00e3o Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png","datePublished":"2024-01-26T22:30:39+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#primaryimage","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2024\/01\/Educadoras-Jacqueline-e-Patricia-abordam-o-tema-Acolhimento-Emocional.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ossjb\/acolhimento-emocional-e-tema-de-formacao-da-obra-social-sao-joao-bosco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ossjb\/"},{"@type":"ListItem","position":2,"name":"Acolhimento emocional \u00e9 tema de forma\u00e7\u00e3o da Obra Social S\u00e3o Jo\u00e3o Bosco"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ossjb\/#website","url":"https:\/\/salesianossp.org.br\/ossjb\/","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ossjb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","url":"https:\/\/salesianossp.org.br\/ossjb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","width":185,"height":56,"caption":"Obra Social S\u00e3o Jo\u00e3o Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSJBCampinas\/","https:\/\/www.instagram.com\/ossjbcampinas\/","https:\/\/www.youtube.com\/channel\/UClNa7qdZCtP9uzs5b0nG2LQ\/featured"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/ossjb\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/5806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/comments?post=5806"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/5806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media\/5807"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media?parent=5806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/categories?post=5806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags?post=5806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}