{"id":683,"date":"2020-07-02T13:38:36","date_gmt":"2020-07-02T16:38:36","guid":{"rendered":"https:\/\/salesianossp.org.br\/ossjb\/oscampinas\/?p=683"},"modified":"2020-07-02T13:38:36","modified_gmt":"2020-07-02T16:38:36","slug":"horta-domestica-da-saude-fisica-ao-bem-estar-mental","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/","title":{"rendered":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental"},"content":{"rendered":"\n<p><strong>Bem-Estar<\/strong><\/p>\n\n\n\n<p><em>Por Matheus Coimbra<\/em><\/p>\n\n\n\n<p>O m\u00eas de junho foi dedicado a celebrar e pensar sobre o Meio Ambiente e a Obra Social S\u00e3o Jo\u00e3o Bosco, como parte da <em>Don Bosco Green Alliance<\/em>, tamb\u00e9m est\u00e1 interessada nessa discuss\u00e3o e nessa transforma\u00e7\u00e3o. Ao longo de junho, lan\u00e7amos alguns desafios \u00e0queles que se conectam a n\u00f3s e, neste texto, vamos refletir os benef\u00edcios da horta dom\u00e9stica para nossa sa\u00fade f\u00edsica e mental.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Horta como cultura org\u00e2nica<\/h4>\n\n\n\n<p>Com o grande avan\u00e7o da urbaniza\u00e7\u00e3o, cada vez mais colocamos um muro entre a cidade e o natural. Isso \u00e9 muito f\u00e1cil de perceber quando precisamos ir ao mercado comprar uma alface ou um tomate sem ter a menor ideia da onde veio aquele alimento. Isso mostra que h\u00e1 um grande distanciamento entre o que \u00e9 plantado e produzido na parte rural e o que n\u00f3s consumimos dentro de casa. Pensando nisso, muitas pessoas est\u00e3o criando suas pr\u00f3prias hortas dom\u00e9sticas com o intuito de n\u00e3o apenas ter um alimento org\u00e2nico e livre de agrot\u00f3xicos, mas tamb\u00e9m como uma quest\u00e3o est\u00e9tica para a sua casa, hobby e relaxamento.<\/p>\n\n\n\n<p>Um dos grandes benef\u00edcios de uma horta em nossas casas \u00e9 podermos ter alimentos ao alcance de nossas m\u00e3os, saud\u00e1vel e livre de qualquer produto qu\u00edmico que normalmente encontramos nos alimentos de supermercado ou em algum outro lugar que venha de uma grande planta\u00e7\u00e3o de monocultura. Podemos ter facilmente, e em pouco tempo de plantio, alimentos como alface, tomate, r\u00facula, cenoura e diversas ervas de tempero em um espa\u00e7o pequeno, pois sabemos que nem todos possuem espa\u00e7o para uma horta grande em suas casas. Mas devemos lembrar que \u00e9 muito f\u00e1cil construir uma horta em qualquer espa\u00e7o acess\u00edvel dentro das nossas casas ou apartamentos e isso irei explicar logo mais.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra-1024x576.png\" alt=\"\" class=\"wp-image-685\" srcset=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra-1024x576.png 1024w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra-300x169.png 300w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra-768x432.png 768w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra-1536x864.png 1536w, https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/alimento_organico_obra.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto: Blog do P\u00e3o<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Horta como contato direto com a natureza<\/h4>\n\n\n\n<p>Indo por outro ponto de perspectiva, podemos utilizar da horta como meio de relaxamento ou hobby que nos ajuda a desestressar de uma vida corrida que muitos de n\u00f3s passamos durante o dia. Ter esse contato com a natureza, nos ajuda a entender que tudo nessa vida tem um tempo e que diferente do que n\u00f3s vivemos na cidade onde tudo \u00e9 r\u00e1pido e nos \u00e9 dado de uma forma f\u00e1cil, aprendemos que tudo tem uma ordem e um tempo para acontecer. Vivenciando esse contato com a natureza devemos cultivar a paci\u00eancia, o tempo que n\u00f3s temos que esperar por uma semente germinar, crescer e por fim, consumi-la.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Horta em casa<\/h4>\n\n\n\n<p>Na teoria \u00e9 f\u00e1cil, mas como eu posso ter uma horta em minha casa ou apartamento?&nbsp; N\u00e3o precisamos ter um espa\u00e7o muito grande para podermos ter uma horta, existem v\u00e1rias formas de conseguir mesmo em locais pequenos, podemos utilizar de vasos de plantas que s\u00e3o facilmente encontrados, tamb\u00e9m podemos utilizar de garrafas pets ou at\u00e9 mesmos canos de PVC para fazer tais&nbsp; hortas. Outra pergunta que pode aparecer \u00e9: \u201co que eu posso plantar?\u201d existem diversas plantas que n\u00e3o precisam de grandes espa\u00e7os para crescer e que s\u00e3o comest\u00edveis e \u00f3timas para sa\u00fade, um exemplo \u00e9 a hortel\u00e3, alecrim, alface, salsinha, cebolinha, cenoura entre outras.<\/p>\n\n\n\n<p>Fazer e ter uma horta em casa ultrapassa a simples quest\u00e3o de ter um produto org\u00e2nico ao nosso alcance, vai desde a montagem da horta que podemos fazer com os nossos filhos ou com pessoas que moram conosco, passando pela escolha do que vai ser plantado, da observa\u00e7\u00e3o do crescimento do que foi plantado e por fim da colheita do alimento. Tudo isso faz parte de um ciclo da natureza que devemos respeitar e que em troca a natureza nos retribui com bem-estar e sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bem-Estar Por Matheus Coimbra O m\u00eas de junho foi dedicado a celebrar e pensar sobre o Meio Ambiente e a Obra Social S\u00e3o Jo\u00e3o Bosco, como parte da Don Bosco Green Alliance, tamb\u00e9m est\u00e1 interessada nessa discuss\u00e3o e nessa transforma\u00e7\u00e3o. Ao longo de junho, lan\u00e7amos alguns desafios \u00e0queles que se conectam a n\u00f3s e, neste [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423,424],"tags":[425,44,409,371],"class_list":["post-683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-bem-estar","tag-bem-estar","tag-dom-bosco","tag-green-alliance","tag-meio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"og:description\" content=\"Bem-Estar Por Matheus Coimbra O m\u00eas de junho foi dedicado a celebrar e pensar sobre o Meio Ambiente e a Obra Social S\u00e3o Jo\u00e3o Bosco, como parte da Don Bosco Green Alliance, tamb\u00e9m est\u00e1 interessada nessa discuss\u00e3o e nessa transforma\u00e7\u00e3o. Ao longo de junho, lan\u00e7amos alguns desafios \u00e0queles que se conectam a n\u00f3s e, neste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSSJBCampinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T16:38:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucas Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/\"},\"author\":{\"name\":\"Lucas Rodrigues\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\"},\"headline\":\"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental\",\"datePublished\":\"2020-07-02T16:38:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/\"},\"wordCount\":666,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/destaque_horta_casa.png\",\"keywords\":[\"bem-estar\",\"Dom Bosco\",\"green alliance\",\"meio ambiente\"],\"articleSection\":[\"Artigos\",\"Bem Estar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/\",\"name\":\"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/destaque_horta_casa.png\",\"datePublished\":\"2020-07-02T16:38:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/destaque_horta_casa.png\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/destaque_horta_casa.png\",\"width\":1920,\"height\":1080,\"caption\":\"Horta Dom\u00e9stica (Foto: Homepedia)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"width\":185,\"height\":56,\"caption\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSJBCampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ossjbcampinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClNa7qdZCtP9uzs5b0nG2LQ\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/person\\\/4bc2abdbcf1d3120dd16324624dcdb93\",\"name\":\"Lucas Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g\",\"caption\":\"Lucas Rodrigues\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/author\\\/lucas-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/","og_locale":"pt_BR","og_type":"article","og_title":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco","og_description":"Bem-Estar Por Matheus Coimbra O m\u00eas de junho foi dedicado a celebrar e pensar sobre o Meio Ambiente e a Obra Social S\u00e3o Jo\u00e3o Bosco, como parte da Don Bosco Green Alliance, tamb\u00e9m est\u00e1 interessada nessa discuss\u00e3o e nessa transforma\u00e7\u00e3o. Ao longo de junho, lan\u00e7amos alguns desafios \u00e0queles que se conectam a n\u00f3s e, neste [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/","og_site_name":"Obra Social S\u00e3o Jo\u00e3o Bosco","article_publisher":"https:\/\/www.facebook.com\/OSSJBCampinas\/","article_published_time":"2020-07-02T16:38:36+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa-1024x576.png","type":"image\/png"}],"author":"Lucas Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Rodrigues","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/"},"author":{"name":"Lucas Rodrigues","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93"},"headline":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental","datePublished":"2020-07-02T16:38:36+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/"},"wordCount":666,"commentCount":2,"publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa.png","keywords":["bem-estar","Dom Bosco","green alliance","meio ambiente"],"articleSection":["Artigos","Bem Estar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/","url":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/","name":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental - Obra Social S\u00e3o Jo\u00e3o Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa.png","datePublished":"2020-07-02T16:38:36+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#primaryimage","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa.png","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2020\/07\/destaque_horta_casa.png","width":1920,"height":1080,"caption":"Horta Dom\u00e9stica (Foto: Homepedia)"},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ossjb\/horta-domestica-da-saude-fisica-ao-bem-estar-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ossjb\/"},{"@type":"ListItem","position":2,"name":"Horta dom\u00e9stica: da sa\u00fade f\u00edsica ao bem estar mental"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ossjb\/#website","url":"https:\/\/salesianossp.org.br\/ossjb\/","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ossjb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","url":"https:\/\/salesianossp.org.br\/ossjb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","width":185,"height":56,"caption":"Obra Social S\u00e3o Jo\u00e3o Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSJBCampinas\/","https:\/\/www.instagram.com\/ossjbcampinas\/","https:\/\/www.youtube.com\/channel\/UClNa7qdZCtP9uzs5b0nG2LQ\/featured"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/person\/4bc2abdbcf1d3120dd16324624dcdb93","name":"Lucas Rodrigues","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ad9c966c6ed3335d7fffe2c3b88880dd298c0817b71e20a6955c38f2a53f746?s=96&d=mm&r=g","caption":"Lucas Rodrigues"},"url":"https:\/\/salesianossp.org.br\/ossjb\/author\/lucas-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media\/684"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}