{"id":414,"count":1,"description":"","link":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/","name":"posse","slug":"posse","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/\" \/>\n<meta property=\"og:site_name\" content=\"Obra Social S\u00e3o Jo\u00e3o Bosco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/tag\\\/posse\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/tag\\\/posse\\\/\",\"name\":\"Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/tag\\\/posse\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/tag\\\/posse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"posse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#organization\",\"name\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logotipo-obra-social-sao-joao-bosco-color-56.svg\",\"width\":185,\"height\":56,\"caption\":\"Obra Social S\u00e3o Jo\u00e3o Bosco\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/ossjb\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSJBCampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ossjbcampinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClNa7qdZCtP9uzs5b0nG2LQ\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco","og_url":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/","og_site_name":"Obra Social S\u00e3o Jo\u00e3o Bosco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/","url":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/","name":"Arquivo de posse - Obra Social S\u00e3o Jo\u00e3o Bosco","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#website"},"breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/ossjb\/tag\/posse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/ossjb\/"},{"@type":"ListItem","position":2,"name":"posse"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/ossjb\/#website","url":"https:\/\/salesianossp.org.br\/ossjb\/","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/ossjb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/ossjb\/#organization","name":"Obra Social S\u00e3o Jo\u00e3o Bosco","url":"https:\/\/salesianossp.org.br\/ossjb\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","contentUrl":"https:\/\/salesianossp.org.br\/ossjb\/wp-content\/uploads\/2025\/10\/logotipo-obra-social-sao-joao-bosco-color-56.svg","width":185,"height":56,"caption":"Obra Social S\u00e3o Jo\u00e3o Bosco"},"image":{"@id":"https:\/\/salesianossp.org.br\/ossjb\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSJBCampinas\/","https:\/\/www.instagram.com\/ossjbcampinas\/","https:\/\/www.youtube.com\/channel\/UClNa7qdZCtP9uzs5b0nG2LQ\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/salesianossp.org.br\/ossjb\/wp-json\/wp\/v2\/posts?tags=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}