{"id":1970,"date":"2023-05-24T15:00:00","date_gmt":"2023-05-24T18:00:00","guid":{"rendered":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/?p=1970"},"modified":"2023-05-24T15:00:00","modified_gmt":"2023-05-24T18:00:00","slug":"nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/","title":{"rendered":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1"},"content":{"rendered":"\n<p>Entre os dias 04 a 12 de maio, celebramos a novena de Nossa Senhora de F\u00e1tima, a<\/p>\n\n\n\n<p>nossa padroeira. Come\u00e7ando com o ter\u00e7o \u00e0s 18h00 e terminamos com a novena \u00e0s<\/p>\n\n\n\n<p>19h00, todo dia um tema diferente, mas ligado ao tema \u201cServir exemplos de Maria\u201d.<\/p>\n\n\n\n<p>Tivemos com muita alegria padre das paroquias da regi\u00e3o que vieram com muito<\/p>\n\n\n\n<p>carinho celebrar a novena e queremos deixar nosso agradecimento aos padres que<\/p>\n\n\n\n<p>estiveram junto conosco. agradecemos a:<\/p>\n\n\n\n<p>1\u00b0 Dia (4.5): Pe. Donizete \u2013 Tema \u201cQuem me recebe, recebe aquele que me enviou\u201d \u2013<\/p>\n\n\n\n<p>(Ben\u00e7\u00e3o da fam\u00edlia).<\/p>\n\n\n\n<p>2\u00b0 Dia (5.5): Pe. Wagner \u2013 Tema \u201cO Filho da Virgem \u00e9 o Caminho, a Verdade e a Vida\u201d<\/p>\n\n\n\n<p>&#8211; (Ben\u00e7\u00e3o dos filhos).<\/p>\n\n\n\n<p>3\u00b0 Dia (6.5): Pe. Jo\u00e3o Gabriel \u2013 Tema: \u201cA exemplo de Maria aceitar a f\u00e9\u201d \u2013 (Ben\u00e7\u00e3o<\/p>\n\n\n\n<p>das mulheres gravidas) .<\/p>\n\n\n\n<p>4\u00b0 Dia (7.5): Pe. Rangel \u2013 Tema: \u201cO humano morada de Deus\u201d \u2013 (Ben\u00e7\u00e3o dos objetos<\/p>\n\n\n\n<p>religiosos).<\/p>\n\n\n\n<p>5\u00b0 Dia (8.5): Pe. Alexander \u2013 Tema: \u201cAbertos a a\u00e7\u00e3o do Esp\u00edrito Santo\u201d \u2013 (Ben\u00e7\u00e3o da<\/p>\n\n\n\n<p>\u00e1gua).<\/p>\n\n\n\n<p>6\u00b0 Dia (9.5): Pe. Higa \u2013 Tema: \u201cSolid\u00e1rios e Fraternos\u201d \u2013 (Ben\u00e7\u00e3o dos alimentos).<\/p>\n\n\n\n<p>7\u00b0 Dia (10.5): Pe. Carlos \u2013 Tema: \u201cJesus \u00e9 a videira e n\u00f3s os ramos\u201d \u2013 (Ben\u00e7\u00e3o das<\/p>\n\n\n\n<p>Velas).<\/p>\n\n\n\n<p>8\u00b0 Dia (11.5): Pe. Higa \u2013 Tema: \u201cSeguir por amor\u201d \u2013 (Ora\u00e7\u00e3o pelas voca\u00e7\u00f5es).<\/p>\n\n\n\n<p>9\u00b0 Dia (12.5): Pe. Luiz \u2013 Tema: \u201cO maior mandamento\u201d \u2013 (Ben\u00e7\u00e3o das chaves).<\/p>\n\n\n\n<p>No dia 13 de maio, celebramos o dia da nossa padroeira com missa \u00e1s 08h celebrada<\/p>\n\n\n\n<p>pelo monge beneditino Dom Jo\u00e3o Evangelista, \u00e1s 12h celebrada pelo Pe. Vagner de<\/p>\n\n\n\n<p>Medeiros, depois \u00e1s 18h com o Pe. Jo\u00e3o Gabriel e finalizando com \u00e1s 19h30 com o<\/p>\n\n\n\n<p>padre Evaristo Higa e tivemos pela primeira vez, a venda do bolo de Nossa Senhora<\/p>\n\n\n\n<p>de F\u00e1tima.<\/p>\n\n\n\n<p>Pamela Aparecida \u2013 Pascom, Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 04 a 12 de maio, celebramos a novena de Nossa Senhora de F\u00e1tima, a nossa padroeira. Come\u00e7ando com o ter\u00e7o \u00e0s 18h00 e terminamos com a novena \u00e0s 19h00, todo dia um tema diferente, mas ligado ao tema \u201cServir exemplos de Maria\u201d. Tivemos com muita alegria padre das paroquias da regi\u00e3o que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1970","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\" \/>\n<meta property=\"og:description\" content=\"Entre os dias 04 a 12 de maio, celebramos a novena de Nossa Senhora de F\u00e1tima, a nossa padroeira. Come\u00e7ando com o ter\u00e7o \u00e0s 18h00 e terminamos com a novena \u00e0s 19h00, todo dia um tema diferente, mas ligado ao tema \u201cServir exemplos de Maria\u201d. Tivemos com muita alegria padre das paroquias da regi\u00e3o que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/\" \/>\n<meta property=\"og:site_name\" content=\"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/matrizguaruja?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T18:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Rog\u00e9rio Bruno B. Saviolli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rog\u00e9rio Bruno B. Saviolli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/\"},\"author\":{\"name\":\"Rog\u00e9rio Bruno B. Saviolli\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#\\\/schema\\\/person\\\/2c28fec5adcdfd0ab2cc8acd388c545d\"},\"headline\":\"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1\",\"datePublished\":\"2023-05-24T18:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/\",\"name\":\"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#website\"},\"datePublished\":\"2023-05-24T18:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/\",\"name\":\"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#organization\",\"name\":\"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-paroquia-n-sra-fes-guaruja.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-paroquia-n-sra-fes-guaruja.svg\",\"width\":184,\"height\":56,\"caption\":\"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/matrizguaruja?mibextid=LQQJ4d\",\"https:\\\/\\\/www.instagram.com\\\/pnsfatima_guaruja\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/#\\\/schema\\\/person\\\/2c28fec5adcdfd0ab2cc8acd388c545d\",\"name\":\"Rog\u00e9rio Bruno B. Saviolli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g\",\"caption\":\"Rog\u00e9rio Bruno B. Saviolli\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parnsfesguaruja\\\/author\\\/rogeriobruno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/","og_locale":"pt_BR","og_type":"article","og_title":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","og_description":"Entre os dias 04 a 12 de maio, celebramos a novena de Nossa Senhora de F\u00e1tima, a nossa padroeira. Come\u00e7ando com o ter\u00e7o \u00e0s 18h00 e terminamos com a novena \u00e0s 19h00, todo dia um tema diferente, mas ligado ao tema \u201cServir exemplos de Maria\u201d. Tivemos com muita alegria padre das paroquias da regi\u00e3o que [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/","og_site_name":"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","article_publisher":"https:\/\/www.facebook.com\/matrizguaruja?mibextid=LQQJ4d","article_published_time":"2023-05-24T18:00:00+00:00","author":"Rog\u00e9rio Bruno B. Saviolli","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rog\u00e9rio Bruno B. Saviolli","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/"},"author":{"name":"Rog\u00e9rio Bruno B. Saviolli","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#\/schema\/person\/2c28fec5adcdfd0ab2cc8acd388c545d"},"headline":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1","datePublished":"2023-05-24T18:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/","url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/","name":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1 - Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#website"},"datePublished":"2023-05-24T18:00:00+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/nossa-senhora-de-fatima-e-celebrada-em-novena-e-festa-na-igreja-matriz-de-guaruja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/"},{"@type":"ListItem","position":2,"name":"Nossa Senhora de F\u00e1tima \u00e9 celebrada em novena e festa na Igreja Matriz de Guaruj\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#website","url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/","name":"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#organization","name":"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro","url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-content\/uploads\/2026\/02\/logo-paroquia-n-sra-fes-guaruja.svg","contentUrl":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-content\/uploads\/2026\/02\/logo-paroquia-n-sra-fes-guaruja.svg","width":184,"height":56,"caption":"Par\u00f3quia Nossa Senhora de F\u00e1tima e Santo Amaro"},"image":{"@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/matrizguaruja?mibextid=LQQJ4d","https:\/\/www.instagram.com\/pnsfatima_guaruja"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/#\/schema\/person\/2c28fec5adcdfd0ab2cc8acd388c545d","name":"Rog\u00e9rio Bruno B. Saviolli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76dd37bc9ed13ac2f3487809fb0c73b7c7ee6cedff8a1b446507d78fd1042cd5?s=96&d=mm&r=g","caption":"Rog\u00e9rio Bruno B. Saviolli"},"url":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/author\/rogeriobruno\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/posts\/1970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/comments?post=1970"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/posts\/1970\/revisions"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/media?parent=1970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/categories?post=1970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/parnsfesguaruja\/wp-json\/wp\/v2\/tags?post=1970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}