{"id":4084,"date":"2024-04-16T19:24:55","date_gmt":"2024-04-16T22:24:55","guid":{"rendered":"https:\/\/salesianossp.org.br\/parscjsp\/?p=4084"},"modified":"2024-04-16T19:24:55","modified_gmt":"2024-04-16T22:24:55","slug":"oratorio-retoma-suas-atividades","status":"publish","type":"post","link":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/","title":{"rendered":"Orat\u00f3rio retoma suas atividades"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Neste S\u00e1bado 06\/04 com grande alegria aconteceu o retorno do Orat\u00f3rio Festivo no Santu\u00e1rio Sagrado Cora\u00e7\u00e3o de Jesus. Foi um momento de compartilhar a alegria e a amizade em esp\u00edrito familiar, esporte e ora\u00e7\u00e3o. Estavam presentes os jovens da par\u00f3quia, catequisandos e os jovens que vieram do entorno do bairro. Agradecemos a presen\u00e7a e ajuda da ADMA e AJS.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"4089\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/435988990_736139185370142_156765740584574918_n-819x1024.jpg\" alt=\"\" class=\"wp-image-4089\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/435988990_736139185370142_156765740584574918_n-819x1024.jpg 819w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/435988990_736139185370142_156765740584574918_n-240x300.jpg 240w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/435988990_736139185370142_156765740584574918_n-768x960.jpg 768w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/435988990_736139185370142_156765740584574918_n.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"652\" height=\"815\" data-id=\"4086\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436356643_736139182036809_6446259657669766740_n.jpg\" alt=\"\" class=\"wp-image-4086\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436356643_736139182036809_6446259657669766740_n.jpg 652w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436356643_736139182036809_6446259657669766740_n-240x300.jpg 240w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"4088\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n-819x1024.jpg\" alt=\"\" class=\"wp-image-4088\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n-819x1024.jpg 819w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n-240x300.jpg 240w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n-768x960.jpg 768w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"4090\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436428314_736139192036808_4809347830862463604_n-819x1024.jpg\" alt=\"\" class=\"wp-image-4090\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436428314_736139192036808_4809347830862463604_n-819x1024.jpg 819w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436428314_736139192036808_4809347830862463604_n-240x300.jpg 240w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436428314_736139192036808_4809347830862463604_n-768x960.jpg 768w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436428314_736139192036808_4809347830862463604_n.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"867\" data-id=\"4087\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800027_736139195370141_7186861314752516953_n.jpg\" alt=\"\" class=\"wp-image-4087\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800027_736139195370141_7186861314752516953_n.jpg 694w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800027_736139195370141_7186861314752516953_n-240x300.jpg 240w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"616\" height=\"769\" data-id=\"4085\" src=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800449_736139178703476_551973552927274721_n.jpg\" alt=\"\" class=\"wp-image-4085\" srcset=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800449_736139178703476_551973552927274721_n.jpg 616w, https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436800449_736139178703476_551973552927274721_n-240x300.jpg 240w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Neste S\u00e1bado 06\/04 com grande alegria aconteceu o retorno do Orat\u00f3rio Festivo no Santu\u00e1rio Sagrado Cora\u00e7\u00e3o de Jesus. Foi um momento de compartilhar a alegria e a amizade em esp\u00edrito familiar, esporte e ora\u00e7\u00e3o. Estavam presentes os jovens da par\u00f3quia, catequisandos e os jovens que vieram do entorno do bairro. Agradecemos a presen\u00e7a e ajuda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-4084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\" \/>\n<meta property=\"og:description\" content=\"Neste S\u00e1bado 06\/04 com grande alegria aconteceu o retorno do Orat\u00f3rio Festivo no Santu\u00e1rio Sagrado Cora\u00e7\u00e3o de Jesus. Foi um momento de compartilhar a alegria e a amizade em esp\u00edrito familiar, esporte e ora\u00e7\u00e3o. Estavam presentes os jovens da par\u00f3quia, catequisandos e os jovens que vieram do entorno do bairro. Agradecemos a presen\u00e7a e ajuda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/\" \/>\n<meta property=\"og:site_name\" content=\"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/pg\/santuariodosagradocoracaodejesus\/photos\/?ref=page_internal\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T22:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ig.scj.sp@salesianos.com.br\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ig.scj.sp@salesianos.com.br\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/\"},\"author\":{\"name\":\"ig.scj.sp@salesianos.com.br\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#\\\/schema\\\/person\\\/3e05d054e52ac3560a3a6b2eb46df0c9\"},\"headline\":\"Orat\u00f3rio retoma suas atividades\",\"datePublished\":\"2024-04-16T22:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/\"},\"wordCount\":71,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/436358554_736139188703475_8420940353733301942_n.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/\",\"name\":\"Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/436358554_736139188703475_8420940353733301942_n.jpg\",\"datePublished\":\"2024-04-16T22:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/436358554_736139188703475_8420940353733301942_n.jpg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/436358554_736139188703475_8420940353733301942_n.jpg\",\"width\":960,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/oratorio-retoma-suas-atividades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orat\u00f3rio retoma suas atividades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#website\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/\",\"name\":\"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#organization\",\"name\":\"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-pvipar-teste.svg\",\"contentUrl\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-pvipar-teste.svg\",\"width\":206,\"height\":56,\"caption\":\"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus\"},\"image\":{\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/pg\\\/santuariodosagradocoracaodejesus\\\/photos\\\/?ref=page_internal\",\"https:\\\/\\\/www.instagram.com\\\/santuariosagradocoracaodejesus\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@santuariosagradocoracaodejesus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/#\\\/schema\\\/person\\\/3e05d054e52ac3560a3a6b2eb46df0c9\",\"name\":\"ig.scj.sp@salesianos.com.br\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g\",\"caption\":\"ig.scj.sp@salesianos.com.br\"},\"url\":\"https:\\\/\\\/salesianossp.org.br\\\/parscjsp\\\/author\\\/ig-scj-spsalesianos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/","og_locale":"pt_BR","og_type":"article","og_title":"Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","og_description":"Neste S\u00e1bado 06\/04 com grande alegria aconteceu o retorno do Orat\u00f3rio Festivo no Santu\u00e1rio Sagrado Cora\u00e7\u00e3o de Jesus. Foi um momento de compartilhar a alegria e a amizade em esp\u00edrito familiar, esporte e ora\u00e7\u00e3o. Estavam presentes os jovens da par\u00f3quia, catequisandos e os jovens que vieram do entorno do bairro. Agradecemos a presen\u00e7a e ajuda [&hellip;]","og_url":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/","og_site_name":"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","article_publisher":"https:\/\/pt-br.facebook.com\/pg\/santuariodosagradocoracaodejesus\/photos\/?ref=page_internal","article_published_time":"2024-04-16T22:24:55+00:00","og_image":[{"width":960,"height":1200,"url":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg","type":"image\/jpeg"}],"author":"ig.scj.sp@salesianos.com.br","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ig.scj.sp@salesianos.com.br"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#article","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/"},"author":{"name":"ig.scj.sp@salesianos.com.br","@id":"https:\/\/salesianossp.org.br\/parscjsp\/#\/schema\/person\/3e05d054e52ac3560a3a6b2eb46df0c9"},"headline":"Orat\u00f3rio retoma suas atividades","datePublished":"2024-04-16T22:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/"},"wordCount":71,"commentCount":0,"publisher":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/#organization"},"image":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/","url":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/","name":"Orat\u00f3rio retoma suas atividades - Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","isPartOf":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#primaryimage"},"image":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#primaryimage"},"thumbnailUrl":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg","datePublished":"2024-04-16T22:24:55+00:00","breadcrumb":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#primaryimage","url":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg","contentUrl":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2024\/04\/436358554_736139188703475_8420940353733301942_n.jpg","width":960,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/salesianossp.org.br\/parscjsp\/oratorio-retoma-suas-atividades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/salesianossp.org.br\/parscjsp\/"},{"@type":"ListItem","position":2,"name":"Orat\u00f3rio retoma suas atividades"}]},{"@type":"WebSite","@id":"https:\/\/salesianossp.org.br\/parscjsp\/#website","url":"https:\/\/salesianossp.org.br\/parscjsp\/","name":"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","description":"","publisher":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesianossp.org.br\/parscjsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/salesianossp.org.br\/parscjsp\/#organization","name":"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus","url":"https:\/\/salesianossp.org.br\/parscjsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/salesianossp.org.br\/parscjsp\/#\/schema\/logo\/image\/","url":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2026\/02\/logo-pvipar-teste.svg","contentUrl":"https:\/\/salesianossp.org.br\/parscjsp\/wp-content\/uploads\/2026\/02\/logo-pvipar-teste.svg","width":206,"height":56,"caption":"Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus"},"image":{"@id":"https:\/\/salesianossp.org.br\/parscjsp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/pg\/santuariodosagradocoracaodejesus\/photos\/?ref=page_internal","https:\/\/www.instagram.com\/santuariosagradocoracaodejesus\/","https:\/\/www.youtube.com\/@santuariosagradocoracaodejesus"]},{"@type":"Person","@id":"https:\/\/salesianossp.org.br\/parscjsp\/#\/schema\/person\/3e05d054e52ac3560a3a6b2eb46df0c9","name":"ig.scj.sp@salesianos.com.br","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5b465543b1ccda250d91a05646f647dd27bc165a888a6fc5e3e58eb36ab9096?s=96&d=mm&r=g","caption":"ig.scj.sp@salesianos.com.br"},"url":"https:\/\/salesianossp.org.br\/parscjsp\/author\/ig-scj-spsalesianos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/posts\/4084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/comments?post=4084"}],"version-history":[{"count":0,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/posts\/4084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/media\/4088"}],"wp:attachment":[{"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/media?parent=4084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/categories?post=4084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salesianossp.org.br\/parscjsp\/wp-json\/wp\/v2\/tags?post=4084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}